{"id":827,"date":"2022-12-15T17:21:00","date_gmt":"2022-12-15T20:21:00","guid":{"rendered":"https:\/\/amamsul.meutecnicoremoto.com.br\/?p=827"},"modified":"2023-07-09T15:17:14","modified_gmt":"2023-07-09T18:17:14","slug":"primeira-mulher-assume-a-presidencia-da-amamsul","status":"publish","type":"post","link":"https:\/\/amamsul.meutecnicoremoto.com.br\/index.php\/2022\/12\/15\/primeira-mulher-assume-a-presidencia-da-amamsul\/","title":{"rendered":"Primeira mulher assume a presid\u00eancia da AMAMSUL"},"content":{"rendered":"\n<p>Mariel Cavalin dos Santos. Esse \u00e9 o nome da ju\u00edza que assumiu a presid\u00eancia da Associa\u00e7\u00e3o dos Magistrados de Mato Grosso do Sul (AMAMSUL) em 44 anos de exist\u00eancia da entidade associativa, na noite desta quinta-feira (15). A solenidade de posse foi realizada no audit\u00f3rio da Esmagis, na sede campo da entidade.<\/p>\n\n\n\n<p>Com Mariel assumiram a nova diretoria os ju\u00edzes Bruno Palhano Gon\u00e7alves (1\u00ba vice-presidente), C\u00e9sar de Souza Lima (2\u00ba vice-presidente), Katy Braun do Prado (secret\u00e1ria geral), Jorge Tadashi Kuramoto (secret\u00e1rio-adjunto), Marcelo Andrade Campos Silva (1\u00ba tesoureiro), F\u00e1bio Henrique Calazans Ramos (2\u00ba tesoureiro), Rafael Gustavo Mateucci Cassia (diretor de Interior), Idail de Toni Filho (diretoria AmamsuLab), M\u00e1rio Jos\u00e9 Esbalqueiro Jr. (diretor da Esmagis), Juliano Luiz Pereira (diretor de Esportes), Paulo Rodrigues (diretor de Inativos), La\u00edsa de Oliveira Ferneda Marcolino (diretoria da Mulher Magistrada), At\u00edlio C\u00e9sar de Oliveira Jr. (diretor de Patrim\u00f4nio), Francisco Soliman (diretor de Prerrogativas).<\/p>\n\n\n\n<p>No Conselho Deliberativo est\u00e3o Daniel Della Mea Ribeiro, Ant\u00f4nio Adonis Mour\u00e3o Jr., Francisco Vieira de Andrade Neto, Maur\u00edcio Cleber Miglioranzi Santos, Raul Ignatius Nogueira. Como suplentes do Conselho Deliberativo estar\u00e3o C\u00e9zar Luiz Miozzo, Fl\u00e1vio Saad Peron e Marilsa Aparecida da Silva Baptista.<\/p>\n\n\n\n<p>Na transmiss\u00e3o do cargo, Giuliano M\u00e1ximo Martins lembrou do in\u00edcio quando, ainda no meio de uma pandemia movimentada, com muitas m\u00e1scaras e \u00e1lcool gel, a diretoria come\u00e7ou a executar as metas anteriormente planejadas e pensadas. Ele destacou feitos na \u00e1rea administrativa e citou duas grandes conquistas para a associa\u00e7\u00e3o: a fazenda de energia solar e a venda das sedes de Tr\u00eas Lagoas e Coxim. Mencionou o lado associativo, com o retorno das festas e cumprimentou a diretora Social, Larissa Castilho, pelo esmero e disposi\u00e7\u00e3o ao longo do bi\u00eanio ao preparar os eventos.<\/p>\n\n\n\n<p>Giuliano ressaltou ainda o lado esportivo, citou as inova\u00e7\u00f5es, os eventos realizados e agradeceu ao incans\u00e1vel diretor de Esportes, Deyvis Ecco, por integrar os associados esportistas. Citou tamb\u00e9m a cria\u00e7\u00e3o de uma comiss\u00e3o pela diretora de Prerrogativas, Jacqueline Machado, para an\u00e1lise de quest\u00f5es que atormentaram a independ\u00eancia judicial e a afetaram no dia-a-dia dos ju\u00edzes e desembargadores em MS.<\/p>\n\n\n\n<p>Ele n\u00e3o esqueceu os relacionamentos institucionais como o MP, a DP, OAB\/MS, Procuradoria, delegados, Focate, entre outros. \u201cO di\u00e1logo tamb\u00e9m sempre foi muito aberto e franco com outros poderes, notadamente com o parlamento estadual e federal, nos projetos que afetam o Poder Judici\u00e1rio. Esse trabalho, que n\u00e3o pode ser abandonado, cara Mariel, trouxe respeito e credibilidade aos argumentos apresentados, de modo que continue a prosperar e sempre buscar o melhor para a magistratura de todo pa\u00eds\u201d, disse para a colega que responder\u00e1 pela presid\u00eancia da AMAMSUL nos pr\u00f3ximos dois anos.<\/p>\n\n\n\n<p>Finalizando a presta\u00e7\u00e3o de contas, Giuliano sublinhou o harmonioso relacionamento com o Corregedor-Geral de Justi\u00e7a, Des. Luiz Tadeu Barbosa, em raz\u00e3o das diversas rodadas de explana\u00e7\u00e3o e intermedia\u00e7\u00e3o para melhoria do Judici\u00e1rio, e com o presidente do TJMS, Des. Carlos Eduardo Contar, j\u00e1 que em todas as pautas encaminhadas tudo sempre foi tratado com muito respeito.<\/p>\n\n\n\n<p>\u201cDestaco a corriqueira galhardia do Des. Carlos Eduardo Contar, que teve a sensibilidade de atender diversos pleitos da associa\u00e7\u00e3o. Aqui posso ressaltar que, gra\u00e7as \u00e0 proativa atitude da administra\u00e7\u00e3o, ganhamos selo ouro no Pr\u00eamio de qualidade do CNJ, colocando nossa magistratura entre as mais gigantes do pa\u00eds\u201d.<\/p>\n\n\n\n<p>Depois de contextualizar a justi\u00e7a no pa\u00eds, emocionado, Giuliano despediu-se do comando da AMAMSUL. \u201cN\u00e3o posso aqui deixar de agradecer a Deus pela oportunidade \u00fanica, \u00e0 minha amada fam\u00edlia pela compreens\u00e3o e aux\u00edlio em me tornar uma pessoa melhor; aos colegas da diretoria, que muito se esfor\u00e7aram para uma melhor execu\u00e7\u00e3o dos nossos prop\u00f3sitos; aos colaboradores da Amamsul, pessoas fant\u00e1sticas que buscam sempre um atendimento de qualidade. Os resultados nem sempre aparecem na hora em que queremos, entretanto, a entrega foi das maiores, integral e de cora\u00e7\u00e3o, o que vale para tranquilizar o corpo e a alma. Muito h\u00e1 de se fazer nessa nossa destemida associa\u00e7\u00e3o, cuja sauda\u00e7\u00e3o permanece em nossa mem\u00f3ria. Avante AMAMSUL\u201d, concluiu.<\/p>\n\n\n\n<p>Ciente da responsabilidade que assumia, Mariel iniciou seu discurso lembrando que \u00e9 grata a cada passo dado e que se sente honrada pela confian\u00e7a e considera\u00e7\u00e3o depositadas nela para que fosse eleita. \u201c\u00c9 hora de seguir em unidade novamente, pois o objetivo \u00e9 comum e a coes\u00e3o \u00e9 a caracter\u00edstica da consci\u00eancia associativa que nos torna fortes\u201d.<\/p>\n\n\n\n<p>Ao colega Giuliano, que comandou a associa\u00e7\u00e3o nos \u00faltimos dois anos, Mariel agradeceu a dedica\u00e7\u00e3o e enalteceu o trabalho realizado. \u201cPosso afirmar, p\u00fablica e sinceramente, que minha admira\u00e7\u00e3o por voc\u00ea aumentou, Giuliano: sua galhardia, serenidade e altru\u00edsmo s\u00e3o dignos de reconhecimento de que a associa\u00e7\u00e3o se manteve em crescimento e fortalecimento como institui\u00e7\u00e3o. Muito obrigada\u201d.<\/p>\n\n\n\n<p>Mariel confessou ainda que o motivo de ter aceito o desafio da candidatura \u00e0 presid\u00eancia da AMAMSUL foi a causa do associativismo: foi pensando em consolidar os la\u00e7os entre os pares e contribuir pessoalmente para a magistratura do Estado que h\u00e1 23 anos a acolheu que ela se disp\u00f4s a comandar a entidade associativa no pr\u00f3ximo bi\u00eanio.<\/p>\n\n\n\n<p>\u201cO objetivo \u00e9 trabalhar e me esfor\u00e7ar, juntamente com a nova equipe que assume, para buscar a melhoria, a cada dia, na qualidade de vida para os associados e, em especial, no trabalho, o que, em certa medida, trar\u00e1 benef\u00edcios com reflexos positivos na presta\u00e7\u00e3o de um servi\u00e7o cada vez mais eficiente para toda a sociedade sul-mato-grossense\u201d, disse a presidente j\u00e1 empossada.&nbsp;<\/p>\n\n\n\n<p>Depois de mencionar o recebimento do Selo Ouro do CNJ, de falar sobre a capacidade produtiva e o cumprimento de metas impostas \u00e0 magistratura, a nova presidente citou os eixos que nortear\u00e3o sua gest\u00e3o: institucional e de defesa da magistratura, integra\u00e7\u00e3o de aposentados e pensionistas, capacita\u00e7\u00e3o e aprimoramento das pr\u00e1ticas judiciais, social e do patrim\u00f4nio.&nbsp;<\/p>\n\n\n\n<p>\u201cO mote da nossa administra\u00e7\u00e3o ser\u00e1 tamb\u00e9m o Di\u00e1logo e Valoriza\u00e7\u00e3o, ou seja, procuraremos maior integra\u00e7\u00e3o e consenso entre nossos membros, di\u00e1logo e colabora\u00e7\u00e3o com a administra\u00e7\u00e3o do Tribunal para buscar a implementa\u00e7\u00e3o de melhorias necess\u00e1rias, mas, acima de tudo, melhorias poss\u00edveis no \u00e2mbito interno, assim como com os outros poderes constitu\u00eddos: Executivo e Legislativo, com vista a somar e n\u00e3o \u00e0 competi\u00e7\u00e3o\u201d.<\/p>\n\n\n\n<p>Ao final, citou o padre F\u00e1bio de Melo para apontar um ensinamento que carrega consigo. \u201cQuanto mais conscientes do que somos, fazemos e podemos, muito mais pr\u00f3ximos estaremos da realiza\u00e7\u00e3o para a qual fomos projetados. Posso assegurar que h\u00e1 disposi\u00e7\u00e3o para empreender esfor\u00e7os, dialogar e democraticamente para construir solu\u00e7\u00f5es em benef\u00edcio de todos os associados da nossa AMAMSUL. Obrigada\u201d.<\/p>\n\n\n\n<p>Prestigiaram a solenidade de posse os desembargadores Carlos Eduardo Contar, Presidente do TJMS; Sideni Soncini Pimentel, Vice-presidente do TJMS; Luiz Tadeu Barbosa Silva, Corregedor-Geral de Justi\u00e7a; Elizabete Anache, coordenadora da Inf\u00e2ncia e Juventude; Marcos Jos\u00e9 de Brito Rodrigues, Ouvidor Judici\u00e1rio; Odemilson Roberto Castro Fassa, diretor-geral eleito para a Escola Judicial; Vladimir Abreu da Silva e Jaceguara Dantas da Silva, al\u00e9m de magistrados da Capital e do interior e representantes de institui\u00e7\u00f5es, familiares, amigos e convidados.<\/p>\n\n\n\n<p><strong>Conhe\u00e7a &#8211;<\/strong>\u00a0Nascida em Jales (SP), Mariel ingressou na magistratura em novembro de 1999, depois de ser aprovada no XIX Concurso de Provas e T\u00edtulos. Ela Iniciou a carreira designada para atuar na 10\u00aa circunscri\u00e7\u00e3o e maio de 2000 foi promovida para Inoc\u00eancia e depois judicou em Cassil\u00e2ndia, onde ficou de 2001 a 2006, quando foi removida para Aparecida do Taboado.<\/p>\n\n\n\n<p>Em dezembro de 2017, uma nova promo\u00e7\u00e3o a trouxe para a Capital para judicar na 16\u00aa Vara C\u00edvel, onde permanece e de cuja vara ficar\u00e1 afastada para exercer suas fun\u00e7\u00f5es na presid\u00eancia no bi\u00eanio 2023\/2024. \u00c9 formada em Direito pela Faculdade Integradas Riopretense, possui especializa\u00e7\u00e3o em Direito Ambiental e especializa\u00e7\u00e3o em Direito e Antropologia Filos\u00f3fica.<\/p>\n\n\n\n<figure class=\"wp-block-gallery-1 is-layout-flex wp-block-gallery-is-layout-flex\">\n\n<figure><a href=\"https:\/\/amamsul.meutecnicoremoto.com.br\/wp-content\/uploads\/2022\/12\/possemariel.jpg\"><img decoding=\"async\" data-id=\"841\" src=\"https:\/\/amamsul.meutecnicoremoto.com.br\/wp-content\/uploads\/2022\/12\/possemariel.jpg\" alt=\"\"\/><\/a><\/figure>\n\n\n<figure><a href=\"https:\/\/amamsul.meutecnicoremoto.com.br\/wp-content\/uploads\/2022\/12\/posseadonis.jpg\"><img decoding=\"async\" data-id=\"832\" src=\"https:\/\/amamsul.meutecnicoremoto.com.br\/wp-content\/uploads\/2022\/12\/posseadonis.jpg\" alt=\"\"\/><\/a><\/figure>\n\n\n<figure><a href=\"https:\/\/amamsul.meutecnicoremoto.com.br\/wp-content\/uploads\/2022\/12\/possebruno.jpg\"><img decoding=\"async\" data-id=\"833\" src=\"https:\/\/amamsul.meutecnicoremoto.com.br\/wp-content\/uploads\/2022\/12\/possebruno.jpg\" alt=\"\"\/><\/a><\/figure>\n\n\n<figure><a href=\"https:\/\/amamsul.meutecnicoremoto.com.br\/wp-content\/uploads\/2022\/12\/possecesarlima.jpg\"><img decoding=\"async\" data-id=\"834\" src=\"https:\/\/amamsul.meutecnicoremoto.com.br\/wp-content\/uploads\/2022\/12\/possecesarlima.jpg\" alt=\"\"\/><\/a><\/figure>\n\n\n<figure><a href=\"https:\/\/amamsul.meutecnicoremoto.com.br\/wp-content\/uploads\/2022\/12\/possedelamea.jpg\"><img decoding=\"async\" data-id=\"835\" src=\"https:\/\/amamsul.meutecnicoremoto.com.br\/wp-content\/uploads\/2022\/12\/possedelamea.jpg\" alt=\"\"\/><\/a><\/figure>\n\n\n<figure><a href=\"https:\/\/amamsul.meutecnicoremoto.com.br\/wp-content\/uploads\/2022\/12\/posseflavio.jpg\"><img decoding=\"async\" data-id=\"836\" src=\"https:\/\/amamsul.meutecnicoremoto.com.br\/wp-content\/uploads\/2022\/12\/posseflavio.jpg\" alt=\"\"\/><\/a><\/figure>\n\n\n<figure><a href=\"https:\/\/amamsul.meutecnicoremoto.com.br\/wp-content\/uploads\/2022\/12\/possejuliano.jpg\"><img decoding=\"async\" data-id=\"837\" src=\"https:\/\/amamsul.meutecnicoremoto.com.br\/wp-content\/uploads\/2022\/12\/possejuliano.jpg\" alt=\"\"\/><\/a><\/figure>\n\n\n<figure><a href=\"https:\/\/amamsul.meutecnicoremoto.com.br\/wp-content\/uploads\/2022\/12\/possekaty.jpg\"><img decoding=\"async\" data-id=\"838\" src=\"https:\/\/amamsul.meutecnicoremoto.com.br\/wp-content\/uploads\/2022\/12\/possekaty.jpg\" alt=\"\"\/><\/a><\/figure>\n\n\n<figure><a href=\"https:\/\/amamsul.meutecnicoremoto.com.br\/wp-content\/uploads\/2022\/12\/possekuramoto.jpg\"><img decoding=\"async\" data-id=\"839\" src=\"https:\/\/amamsul.meutecnicoremoto.com.br\/wp-content\/uploads\/2022\/12\/possekuramoto.jpg\" alt=\"\"\/><\/a><\/figure>\n\n\n<figure><a href=\"https:\/\/amamsul.meutecnicoremoto.com.br\/wp-content\/uploads\/2022\/12\/possemarceloandrade.jpg\"><img decoding=\"async\" data-id=\"840\" src=\"https:\/\/amamsul.meutecnicoremoto.com.br\/wp-content\/uploads\/2022\/12\/possemarceloandrade.jpg\" alt=\"\"\/><\/a><\/figure>\n\n\n<figure><a href=\"https:\/\/amamsul.meutecnicoremoto.com.br\/wp-content\/uploads\/2022\/12\/possemario.jpg\"><img decoding=\"async\" data-id=\"842\" src=\"https:\/\/amamsul.meutecnicoremoto.com.br\/wp-content\/uploads\/2022\/12\/possemario.jpg\" alt=\"\"\/><\/a><\/figure>\n\n\n<figure><a href=\"https:\/\/amamsul.meutecnicoremoto.com.br\/wp-content\/uploads\/2022\/12\/possemiozzo.jpg\"><img decoding=\"async\" data-id=\"843\" src=\"https:\/\/amamsul.meutecnicoremoto.com.br\/wp-content\/uploads\/2022\/12\/possemiozzo.jpg\" alt=\"\"\/><\/a><\/figure>\n\n\n<figure><a href=\"https:\/\/amamsul.meutecnicoremoto.com.br\/wp-content\/uploads\/2022\/12\/possepaulorod.jpg\"><img decoding=\"async\" data-id=\"844\" src=\"https:\/\/amamsul.meutecnicoremoto.com.br\/wp-content\/uploads\/2022\/12\/possepaulorod.jpg\" alt=\"\"\/><\/a><\/figure>\n\n\n<figure><a href=\"https:\/\/amamsul.meutecnicoremoto.com.br\/wp-content\/uploads\/2022\/12\/possepresidentes.jpg\"><img decoding=\"async\" data-id=\"845\" src=\"https:\/\/amamsul.meutecnicoremoto.com.br\/wp-content\/uploads\/2022\/12\/possepresidentes.jpg\" alt=\"\"\/><\/a><\/figure>\n\n<\/figure>\n","protected":false},"excerpt":{"rendered":"<p>Mariel Cavalin dos Santos. Esse \u00e9 o nome da ju\u00edza que assumiu a presid\u00eancia da Associa\u00e7\u00e3o dos Magistrados de Mato Grosso do Sul (AMAMSUL) em 44 anos de exist\u00eancia da entidade associativa, na noite desta quinta-feira (15). A solenidade de posse foi realizada no audit\u00f3rio da Esmagis, na sede campo da entidade. Com Mariel assumiram [&hellip;]<\/p>\n","protected":false},"author":2,"featured_media":828,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[4],"tags":[],"class_list":["post-827","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-destaques"],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v22.6 (Yoast SEO v26.9) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>Primeira mulher assume a presid\u00eancia da AMAMSUL - AMAMSUL<\/title>\n<meta name=\"robots\" content=\"noindex, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<meta property=\"og:locale\" content=\"pt_BR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Primeira mulher assume a presid\u00eancia da AMAMSUL\" \/>\n<meta property=\"og:description\" content=\"Mariel Cavalin dos Santos. Esse \u00e9 o nome da ju\u00edza que assumiu a presid\u00eancia da Associa\u00e7\u00e3o dos Magistrados de Mato Grosso do Sul (AMAMSUL) em 44 anos de exist\u00eancia da entidade associativa, na noite desta quinta-feira (15). A solenidade de posse foi realizada no audit\u00f3rio da Esmagis, na sede campo da entidade. Com Mariel assumiram [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/amamsul.meutecnicoremoto.com.br\/index.php\/2022\/12\/15\/primeira-mulher-assume-a-presidencia-da-amamsul\/\" \/>\n<meta property=\"og:site_name\" content=\"AMAMSUL\" \/>\n<meta property=\"article:published_time\" content=\"2022-12-15T20:21:00+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2023-07-09T18:17:14+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/amamsul.meutecnicoremoto.com.br\/wp-content\/uploads\/2023\/04\/capapossemariel.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"800\" \/>\n\t<meta property=\"og:image:height\" content=\"550\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Imprensa Amamsul\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Imprensa Amamsul\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. tempo de leitura\" \/>\n\t<meta name=\"twitter:data2\" content=\"10 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\/\/amamsul.meutecnicoremoto.com.br\/index.php\/2022\/12\/15\/primeira-mulher-assume-a-presidencia-da-amamsul\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/amamsul.meutecnicoremoto.com.br\/index.php\/2022\/12\/15\/primeira-mulher-assume-a-presidencia-da-amamsul\/\"},\"author\":{\"name\":\"Imprensa Amamsul\",\"@id\":\"https:\/\/amamsul.meutecnicoremoto.com.br\/#\/schema\/person\/646bfbd1aa4c9c8dc837ed1b59b63b7c\"},\"headline\":\"Primeira mulher assume a presid\u00eancia da AMAMSUL\",\"datePublished\":\"2022-12-15T20:21:00+00:00\",\"dateModified\":\"2023-07-09T18:17:14+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/amamsul.meutecnicoremoto.com.br\/index.php\/2022\/12\/15\/primeira-mulher-assume-a-presidencia-da-amamsul\/\"},\"wordCount\":1371,\"commentCount\":0,\"image\":{\"@id\":\"https:\/\/amamsul.meutecnicoremoto.com.br\/index.php\/2022\/12\/15\/primeira-mulher-assume-a-presidencia-da-amamsul\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/amamsul.meutecnicoremoto.com.br\/wp-content\/uploads\/2023\/04\/capapossemariel.jpg\",\"articleSection\":[\"Destaques\"],\"inLanguage\":\"pt-BR\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\/\/amamsul.meutecnicoremoto.com.br\/index.php\/2022\/12\/15\/primeira-mulher-assume-a-presidencia-da-amamsul\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/amamsul.meutecnicoremoto.com.br\/index.php\/2022\/12\/15\/primeira-mulher-assume-a-presidencia-da-amamsul\/\",\"url\":\"https:\/\/amamsul.meutecnicoremoto.com.br\/index.php\/2022\/12\/15\/primeira-mulher-assume-a-presidencia-da-amamsul\/\",\"name\":\"Primeira mulher assume a presid\u00eancia da AMAMSUL - AMAMSUL\",\"isPartOf\":{\"@id\":\"https:\/\/amamsul.meutecnicoremoto.com.br\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/amamsul.meutecnicoremoto.com.br\/index.php\/2022\/12\/15\/primeira-mulher-assume-a-presidencia-da-amamsul\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/amamsul.meutecnicoremoto.com.br\/index.php\/2022\/12\/15\/primeira-mulher-assume-a-presidencia-da-amamsul\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/amamsul.meutecnicoremoto.com.br\/wp-content\/uploads\/2023\/04\/capapossemariel.jpg\",\"datePublished\":\"2022-12-15T20:21:00+00:00\",\"dateModified\":\"2023-07-09T18:17:14+00:00\",\"author\":{\"@id\":\"https:\/\/amamsul.meutecnicoremoto.com.br\/#\/schema\/person\/646bfbd1aa4c9c8dc837ed1b59b63b7c\"},\"breadcrumb\":{\"@id\":\"https:\/\/amamsul.meutecnicoremoto.com.br\/index.php\/2022\/12\/15\/primeira-mulher-assume-a-presidencia-da-amamsul\/#breadcrumb\"},\"inLanguage\":\"pt-BR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/amamsul.meutecnicoremoto.com.br\/index.php\/2022\/12\/15\/primeira-mulher-assume-a-presidencia-da-amamsul\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\/\/amamsul.meutecnicoremoto.com.br\/index.php\/2022\/12\/15\/primeira-mulher-assume-a-presidencia-da-amamsul\/#primaryimage\",\"url\":\"https:\/\/amamsul.meutecnicoremoto.com.br\/wp-content\/uploads\/2023\/04\/capapossemariel.jpg\",\"contentUrl\":\"https:\/\/amamsul.meutecnicoremoto.com.br\/wp-content\/uploads\/2023\/04\/capapossemariel.jpg\",\"width\":800,\"height\":550},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/amamsul.meutecnicoremoto.com.br\/index.php\/2022\/12\/15\/primeira-mulher-assume-a-presidencia-da-amamsul\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"In\u00edcio\",\"item\":\"https:\/\/amamsul.meutecnicoremoto.com.br\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Primeira mulher assume a presid\u00eancia da AMAMSUL\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/amamsul.meutecnicoremoto.com.br\/#website\",\"url\":\"https:\/\/amamsul.meutecnicoremoto.com.br\/\",\"name\":\"AMAMSUL\",\"description\":\"Associa\u00e7\u00e3o dos Magistrados de Mato Grosso do Sul\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/amamsul.meutecnicoremoto.com.br\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"pt-BR\"},{\"@type\":\"Person\",\"@id\":\"https:\/\/amamsul.meutecnicoremoto.com.br\/#\/schema\/person\/646bfbd1aa4c9c8dc837ed1b59b63b7c\",\"name\":\"Imprensa Amamsul\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\/\/amamsul.meutecnicoremoto.com.br\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/62be2d8c4f042719726d6b6a4e1a0942261c1a03354967aa17e58b127147014f?s=96&d=mm&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/62be2d8c4f042719726d6b6a4e1a0942261c1a03354967aa17e58b127147014f?s=96&d=mm&r=g\",\"caption\":\"Imprensa Amamsul\"},\"url\":\"https:\/\/amamsul.meutecnicoremoto.com.br\/index.php\/author\/imprensa-amamsul\/\"}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"Primeira mulher assume a presid\u00eancia da AMAMSUL - AMAMSUL","robots":{"index":"noindex","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"og_locale":"pt_BR","og_type":"article","og_title":"Primeira mulher assume a presid\u00eancia da AMAMSUL","og_description":"Mariel Cavalin dos Santos. Esse \u00e9 o nome da ju\u00edza que assumiu a presid\u00eancia da Associa\u00e7\u00e3o dos Magistrados de Mato Grosso do Sul (AMAMSUL) em 44 anos de exist\u00eancia da entidade associativa, na noite desta quinta-feira (15). A solenidade de posse foi realizada no audit\u00f3rio da Esmagis, na sede campo da entidade. Com Mariel assumiram [&hellip;]","og_url":"https:\/\/amamsul.meutecnicoremoto.com.br\/index.php\/2022\/12\/15\/primeira-mulher-assume-a-presidencia-da-amamsul\/","og_site_name":"AMAMSUL","article_published_time":"2022-12-15T20:21:00+00:00","article_modified_time":"2023-07-09T18:17:14+00:00","og_image":[{"width":800,"height":550,"url":"https:\/\/amamsul.meutecnicoremoto.com.br\/wp-content\/uploads\/2023\/04\/capapossemariel.jpg","type":"image\/jpeg"}],"author":"Imprensa Amamsul","twitter_card":"summary_large_image","twitter_misc":{"Escrito por":"Imprensa Amamsul","Est. tempo de leitura":"10 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/amamsul.meutecnicoremoto.com.br\/index.php\/2022\/12\/15\/primeira-mulher-assume-a-presidencia-da-amamsul\/#article","isPartOf":{"@id":"https:\/\/amamsul.meutecnicoremoto.com.br\/index.php\/2022\/12\/15\/primeira-mulher-assume-a-presidencia-da-amamsul\/"},"author":{"name":"Imprensa Amamsul","@id":"https:\/\/amamsul.meutecnicoremoto.com.br\/#\/schema\/person\/646bfbd1aa4c9c8dc837ed1b59b63b7c"},"headline":"Primeira mulher assume a presid\u00eancia da AMAMSUL","datePublished":"2022-12-15T20:21:00+00:00","dateModified":"2023-07-09T18:17:14+00:00","mainEntityOfPage":{"@id":"https:\/\/amamsul.meutecnicoremoto.com.br\/index.php\/2022\/12\/15\/primeira-mulher-assume-a-presidencia-da-amamsul\/"},"wordCount":1371,"commentCount":0,"image":{"@id":"https:\/\/amamsul.meutecnicoremoto.com.br\/index.php\/2022\/12\/15\/primeira-mulher-assume-a-presidencia-da-amamsul\/#primaryimage"},"thumbnailUrl":"https:\/\/amamsul.meutecnicoremoto.com.br\/wp-content\/uploads\/2023\/04\/capapossemariel.jpg","articleSection":["Destaques"],"inLanguage":"pt-BR","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/amamsul.meutecnicoremoto.com.br\/index.php\/2022\/12\/15\/primeira-mulher-assume-a-presidencia-da-amamsul\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/amamsul.meutecnicoremoto.com.br\/index.php\/2022\/12\/15\/primeira-mulher-assume-a-presidencia-da-amamsul\/","url":"https:\/\/amamsul.meutecnicoremoto.com.br\/index.php\/2022\/12\/15\/primeira-mulher-assume-a-presidencia-da-amamsul\/","name":"Primeira mulher assume a presid\u00eancia da AMAMSUL - AMAMSUL","isPartOf":{"@id":"https:\/\/amamsul.meutecnicoremoto.com.br\/#website"},"primaryImageOfPage":{"@id":"https:\/\/amamsul.meutecnicoremoto.com.br\/index.php\/2022\/12\/15\/primeira-mulher-assume-a-presidencia-da-amamsul\/#primaryimage"},"image":{"@id":"https:\/\/amamsul.meutecnicoremoto.com.br\/index.php\/2022\/12\/15\/primeira-mulher-assume-a-presidencia-da-amamsul\/#primaryimage"},"thumbnailUrl":"https:\/\/amamsul.meutecnicoremoto.com.br\/wp-content\/uploads\/2023\/04\/capapossemariel.jpg","datePublished":"2022-12-15T20:21:00+00:00","dateModified":"2023-07-09T18:17:14+00:00","author":{"@id":"https:\/\/amamsul.meutecnicoremoto.com.br\/#\/schema\/person\/646bfbd1aa4c9c8dc837ed1b59b63b7c"},"breadcrumb":{"@id":"https:\/\/amamsul.meutecnicoremoto.com.br\/index.php\/2022\/12\/15\/primeira-mulher-assume-a-presidencia-da-amamsul\/#breadcrumb"},"inLanguage":"pt-BR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/amamsul.meutecnicoremoto.com.br\/index.php\/2022\/12\/15\/primeira-mulher-assume-a-presidencia-da-amamsul\/"]}]},{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/amamsul.meutecnicoremoto.com.br\/index.php\/2022\/12\/15\/primeira-mulher-assume-a-presidencia-da-amamsul\/#primaryimage","url":"https:\/\/amamsul.meutecnicoremoto.com.br\/wp-content\/uploads\/2023\/04\/capapossemariel.jpg","contentUrl":"https:\/\/amamsul.meutecnicoremoto.com.br\/wp-content\/uploads\/2023\/04\/capapossemariel.jpg","width":800,"height":550},{"@type":"BreadcrumbList","@id":"https:\/\/amamsul.meutecnicoremoto.com.br\/index.php\/2022\/12\/15\/primeira-mulher-assume-a-presidencia-da-amamsul\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"In\u00edcio","item":"https:\/\/amamsul.meutecnicoremoto.com.br\/"},{"@type":"ListItem","position":2,"name":"Primeira mulher assume a presid\u00eancia da AMAMSUL"}]},{"@type":"WebSite","@id":"https:\/\/amamsul.meutecnicoremoto.com.br\/#website","url":"https:\/\/amamsul.meutecnicoremoto.com.br\/","name":"AMAMSUL","description":"Associa\u00e7\u00e3o dos Magistrados de Mato Grosso do Sul","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/amamsul.meutecnicoremoto.com.br\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"pt-BR"},{"@type":"Person","@id":"https:\/\/amamsul.meutecnicoremoto.com.br\/#\/schema\/person\/646bfbd1aa4c9c8dc837ed1b59b63b7c","name":"Imprensa Amamsul","image":{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/amamsul.meutecnicoremoto.com.br\/#\/schema\/person\/image\/","url":"https:\/\/secure.gravatar.com\/avatar\/62be2d8c4f042719726d6b6a4e1a0942261c1a03354967aa17e58b127147014f?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/62be2d8c4f042719726d6b6a4e1a0942261c1a03354967aa17e58b127147014f?s=96&d=mm&r=g","caption":"Imprensa Amamsul"},"url":"https:\/\/amamsul.meutecnicoremoto.com.br\/index.php\/author\/imprensa-amamsul\/"}]}},"_links":{"self":[{"href":"https:\/\/amamsul.meutecnicoremoto.com.br\/index.php\/wp-json\/wp\/v2\/posts\/827","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/amamsul.meutecnicoremoto.com.br\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/amamsul.meutecnicoremoto.com.br\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/amamsul.meutecnicoremoto.com.br\/index.php\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/amamsul.meutecnicoremoto.com.br\/index.php\/wp-json\/wp\/v2\/comments?post=827"}],"version-history":[{"count":7,"href":"https:\/\/amamsul.meutecnicoremoto.com.br\/index.php\/wp-json\/wp\/v2\/posts\/827\/revisions"}],"predecessor-version":[{"id":1317,"href":"https:\/\/amamsul.meutecnicoremoto.com.br\/index.php\/wp-json\/wp\/v2\/posts\/827\/revisions\/1317"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/amamsul.meutecnicoremoto.com.br\/index.php\/wp-json\/wp\/v2\/media\/828"}],"wp:attachment":[{"href":"https:\/\/amamsul.meutecnicoremoto.com.br\/index.php\/wp-json\/wp\/v2\/media?parent=827"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/amamsul.meutecnicoremoto.com.br\/index.php\/wp-json\/wp\/v2\/categories?post=827"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/amamsul.meutecnicoremoto.com.br\/index.php\/wp-json\/wp\/v2\/tags?post=827"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}