{"id":1638,"date":"2024-04-13T12:21:00","date_gmt":"2024-04-13T15:21:00","guid":{"rendered":"https:\/\/amamsul.meutecnicoremoto.com.br\/?p=1638"},"modified":"2024-05-29T12:22:38","modified_gmt":"2024-05-29T15:22:38","slug":"tjms-e-destaque-nacional-na-realizacao-de-juris","status":"publish","type":"post","link":"https:\/\/amamsul.meutecnicoremoto.com.br\/index.php\/2024\/04\/13\/tjms-e-destaque-nacional-na-realizacao-de-juris\/","title":{"rendered":"TJMS \u00e9 destaque nacional na realiza\u00e7\u00e3o de j\u00faris"},"content":{"rendered":"\n<p>O TJMS, por seus magistrados e servidores, mais uma vez se mostra vanguardista na celeridade de julgamentos afetos ao tribunal do j\u00fari.<\/p>\n\n\n\n<p><br>O Programa do&nbsp;CNJ denominado \u201cM\u00eas Nacional do J\u00fari\u201d, criado pela Portaria n. 69\/02017, tem sido aplicado concretamente em MS e os resultados est\u00e3o demonstrados no Relat\u00f3rio M\u00eas Nacional do J\u00fari 2023, publicado pelo CNJ.<\/p>\n\n\n\n<p><br>De acordo com os levantamentos estat\u00edsticos, o TJMS apresentou o maior quantitativo de processos pautados e de sess\u00f5es realizadas.<br>Em 2023, ocorreram 538 sess\u00f5es em MS e 110 em Campo Grande, o que comprova, segundo o juiz Carlos Alberto Garcete, titular da 1 vara do Tribunal do J\u00fari da Comarca de Campo Grande, que os magistrados do Estado seguem comprometidos com as metas nacionais e com a efici\u00eancia na entrega da presta\u00e7\u00e3o jurisdicional.<\/p>\n\n\n\n<p><a href=\"https:\/\/www.amamsul.com.br\/site\/images\/relatorio-mes-juri-2023-02.04.2024.pdf\">Relat\u00f3rio Juri M\u00eas 04-24<\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>O TJMS, por seus magistrados e servidores, mais uma vez se mostra vanguardista na celeridade de julgamentos afetos ao tribunal do j\u00fari. O Programa do&nbsp;CNJ denominado \u201cM\u00eas Nacional do J\u00fari\u201d, criado pela Portaria n. 69\/02017, tem sido aplicado concretamente em MS e os resultados est\u00e3o demonstrados no Relat\u00f3rio M\u00eas Nacional do J\u00fari 2023, publicado pelo [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":1640,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[4,5],"tags":[],"class_list":["post-1638","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-destaques","category-noticias"],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v22.6 (Yoast SEO v26.9) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>TJMS \u00e9 destaque nacional na realiza\u00e7\u00e3o de j\u00faris - AMAMSUL<\/title>\n<meta name=\"robots\" content=\"noindex, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<meta property=\"og:locale\" content=\"pt_BR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"TJMS \u00e9 destaque nacional na realiza\u00e7\u00e3o de j\u00faris\" \/>\n<meta property=\"og:description\" content=\"O TJMS, por seus magistrados e servidores, mais uma vez se mostra vanguardista na celeridade de julgamentos afetos ao tribunal do j\u00fari. O Programa do&nbsp;CNJ denominado \u201cM\u00eas Nacional do J\u00fari\u201d, criado pela Portaria n. 69\/02017, tem sido aplicado concretamente em MS e os resultados est\u00e3o demonstrados no Relat\u00f3rio M\u00eas Nacional do J\u00fari 2023, publicado pelo [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/amamsul.meutecnicoremoto.com.br\/index.php\/2024\/04\/13\/tjms-e-destaque-nacional-na-realizacao-de-juris\/\" \/>\n<meta property=\"og:site_name\" content=\"AMAMSUL\" \/>\n<meta property=\"article:published_time\" content=\"2024-04-13T15:21:00+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2024-05-29T15:22:38+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/amamsul.meutecnicoremoto.com.br\/wp-content\/uploads\/2024\/05\/TribunalDoJuri_1.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1080\" \/>\n\t<meta property=\"og:image:height\" content=\"720\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"hermes\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"hermes\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. tempo de leitura\" \/>\n\t<meta name=\"twitter:data2\" content=\"1 minuto\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\/\/amamsul.meutecnicoremoto.com.br\/index.php\/2024\/04\/13\/tjms-e-destaque-nacional-na-realizacao-de-juris\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/amamsul.meutecnicoremoto.com.br\/index.php\/2024\/04\/13\/tjms-e-destaque-nacional-na-realizacao-de-juris\/\"},\"author\":{\"name\":\"hermes\",\"@id\":\"https:\/\/amamsul.meutecnicoremoto.com.br\/#\/schema\/person\/52d48e1503c287dad33f5b5152a412c3\"},\"headline\":\"TJMS \u00e9 destaque nacional na realiza\u00e7\u00e3o de j\u00faris\",\"datePublished\":\"2024-04-13T15:21:00+00:00\",\"dateModified\":\"2024-05-29T15:22:38+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/amamsul.meutecnicoremoto.com.br\/index.php\/2024\/04\/13\/tjms-e-destaque-nacional-na-realizacao-de-juris\/\"},\"wordCount\":153,\"commentCount\":0,\"image\":{\"@id\":\"https:\/\/amamsul.meutecnicoremoto.com.br\/index.php\/2024\/04\/13\/tjms-e-destaque-nacional-na-realizacao-de-juris\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/amamsul.meutecnicoremoto.com.br\/wp-content\/uploads\/2024\/05\/TribunalDoJuri_1.jpg\",\"articleSection\":[\"Destaques\",\"Not\u00edcias\"],\"inLanguage\":\"pt-BR\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\/\/amamsul.meutecnicoremoto.com.br\/index.php\/2024\/04\/13\/tjms-e-destaque-nacional-na-realizacao-de-juris\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/amamsul.meutecnicoremoto.com.br\/index.php\/2024\/04\/13\/tjms-e-destaque-nacional-na-realizacao-de-juris\/\",\"url\":\"https:\/\/amamsul.meutecnicoremoto.com.br\/index.php\/2024\/04\/13\/tjms-e-destaque-nacional-na-realizacao-de-juris\/\",\"name\":\"TJMS \u00e9 destaque nacional na realiza\u00e7\u00e3o de j\u00faris - AMAMSUL\",\"isPartOf\":{\"@id\":\"https:\/\/amamsul.meutecnicoremoto.com.br\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/amamsul.meutecnicoremoto.com.br\/index.php\/2024\/04\/13\/tjms-e-destaque-nacional-na-realizacao-de-juris\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/amamsul.meutecnicoremoto.com.br\/index.php\/2024\/04\/13\/tjms-e-destaque-nacional-na-realizacao-de-juris\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/amamsul.meutecnicoremoto.com.br\/wp-content\/uploads\/2024\/05\/TribunalDoJuri_1.jpg\",\"datePublished\":\"2024-04-13T15:21:00+00:00\",\"dateModified\":\"2024-05-29T15:22:38+00:00\",\"author\":{\"@id\":\"https:\/\/amamsul.meutecnicoremoto.com.br\/#\/schema\/person\/52d48e1503c287dad33f5b5152a412c3\"},\"breadcrumb\":{\"@id\":\"https:\/\/amamsul.meutecnicoremoto.com.br\/index.php\/2024\/04\/13\/tjms-e-destaque-nacional-na-realizacao-de-juris\/#breadcrumb\"},\"inLanguage\":\"pt-BR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/amamsul.meutecnicoremoto.com.br\/index.php\/2024\/04\/13\/tjms-e-destaque-nacional-na-realizacao-de-juris\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\/\/amamsul.meutecnicoremoto.com.br\/index.php\/2024\/04\/13\/tjms-e-destaque-nacional-na-realizacao-de-juris\/#primaryimage\",\"url\":\"https:\/\/amamsul.meutecnicoremoto.com.br\/wp-content\/uploads\/2024\/05\/TribunalDoJuri_1.jpg\",\"contentUrl\":\"https:\/\/amamsul.meutecnicoremoto.com.br\/wp-content\/uploads\/2024\/05\/TribunalDoJuri_1.jpg\",\"width\":1080,\"height\":720,\"caption\":\"xr:d:DAGCTRkvWsw:2,j:2176789266169390485,t:24041313\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/amamsul.meutecnicoremoto.com.br\/index.php\/2024\/04\/13\/tjms-e-destaque-nacional-na-realizacao-de-juris\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"In\u00edcio\",\"item\":\"https:\/\/amamsul.meutecnicoremoto.com.br\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"TJMS \u00e9 destaque nacional na realiza\u00e7\u00e3o de j\u00faris\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/amamsul.meutecnicoremoto.com.br\/#website\",\"url\":\"https:\/\/amamsul.meutecnicoremoto.com.br\/\",\"name\":\"AMAMSUL\",\"description\":\"Associa\u00e7\u00e3o dos Magistrados de Mato Grosso do Sul\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/amamsul.meutecnicoremoto.com.br\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"pt-BR\"},{\"@type\":\"Person\",\"@id\":\"https:\/\/amamsul.meutecnicoremoto.com.br\/#\/schema\/person\/52d48e1503c287dad33f5b5152a412c3\",\"name\":\"hermes\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\/\/amamsul.meutecnicoremoto.com.br\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/39483e59aab29b78c1c51fa7c391c7ea16952951fc2d61ae410507457c09593d?s=96&d=mm&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/39483e59aab29b78c1c51fa7c391c7ea16952951fc2d61ae410507457c09593d?s=96&d=mm&r=g\",\"caption\":\"hermes\"},\"sameAs\":[\"https:\/\/amamsul.meutecnicoremoto.com.br\"],\"url\":\"https:\/\/amamsul.meutecnicoremoto.com.br\/index.php\/author\/hermes\/\"}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"TJMS \u00e9 destaque nacional na realiza\u00e7\u00e3o de j\u00faris - AMAMSUL","robots":{"index":"noindex","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"og_locale":"pt_BR","og_type":"article","og_title":"TJMS \u00e9 destaque nacional na realiza\u00e7\u00e3o de j\u00faris","og_description":"O TJMS, por seus magistrados e servidores, mais uma vez se mostra vanguardista na celeridade de julgamentos afetos ao tribunal do j\u00fari. O Programa do&nbsp;CNJ denominado \u201cM\u00eas Nacional do J\u00fari\u201d, criado pela Portaria n. 69\/02017, tem sido aplicado concretamente em MS e os resultados est\u00e3o demonstrados no Relat\u00f3rio M\u00eas Nacional do J\u00fari 2023, publicado pelo [&hellip;]","og_url":"https:\/\/amamsul.meutecnicoremoto.com.br\/index.php\/2024\/04\/13\/tjms-e-destaque-nacional-na-realizacao-de-juris\/","og_site_name":"AMAMSUL","article_published_time":"2024-04-13T15:21:00+00:00","article_modified_time":"2024-05-29T15:22:38+00:00","og_image":[{"width":1080,"height":720,"url":"https:\/\/amamsul.meutecnicoremoto.com.br\/wp-content\/uploads\/2024\/05\/TribunalDoJuri_1.jpg","type":"image\/jpeg"}],"author":"hermes","twitter_card":"summary_large_image","twitter_misc":{"Escrito por":"hermes","Est. tempo de leitura":"1 minuto"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/amamsul.meutecnicoremoto.com.br\/index.php\/2024\/04\/13\/tjms-e-destaque-nacional-na-realizacao-de-juris\/#article","isPartOf":{"@id":"https:\/\/amamsul.meutecnicoremoto.com.br\/index.php\/2024\/04\/13\/tjms-e-destaque-nacional-na-realizacao-de-juris\/"},"author":{"name":"hermes","@id":"https:\/\/amamsul.meutecnicoremoto.com.br\/#\/schema\/person\/52d48e1503c287dad33f5b5152a412c3"},"headline":"TJMS \u00e9 destaque nacional na realiza\u00e7\u00e3o de j\u00faris","datePublished":"2024-04-13T15:21:00+00:00","dateModified":"2024-05-29T15:22:38+00:00","mainEntityOfPage":{"@id":"https:\/\/amamsul.meutecnicoremoto.com.br\/index.php\/2024\/04\/13\/tjms-e-destaque-nacional-na-realizacao-de-juris\/"},"wordCount":153,"commentCount":0,"image":{"@id":"https:\/\/amamsul.meutecnicoremoto.com.br\/index.php\/2024\/04\/13\/tjms-e-destaque-nacional-na-realizacao-de-juris\/#primaryimage"},"thumbnailUrl":"https:\/\/amamsul.meutecnicoremoto.com.br\/wp-content\/uploads\/2024\/05\/TribunalDoJuri_1.jpg","articleSection":["Destaques","Not\u00edcias"],"inLanguage":"pt-BR","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/amamsul.meutecnicoremoto.com.br\/index.php\/2024\/04\/13\/tjms-e-destaque-nacional-na-realizacao-de-juris\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/amamsul.meutecnicoremoto.com.br\/index.php\/2024\/04\/13\/tjms-e-destaque-nacional-na-realizacao-de-juris\/","url":"https:\/\/amamsul.meutecnicoremoto.com.br\/index.php\/2024\/04\/13\/tjms-e-destaque-nacional-na-realizacao-de-juris\/","name":"TJMS \u00e9 destaque nacional na realiza\u00e7\u00e3o de j\u00faris - AMAMSUL","isPartOf":{"@id":"https:\/\/amamsul.meutecnicoremoto.com.br\/#website"},"primaryImageOfPage":{"@id":"https:\/\/amamsul.meutecnicoremoto.com.br\/index.php\/2024\/04\/13\/tjms-e-destaque-nacional-na-realizacao-de-juris\/#primaryimage"},"image":{"@id":"https:\/\/amamsul.meutecnicoremoto.com.br\/index.php\/2024\/04\/13\/tjms-e-destaque-nacional-na-realizacao-de-juris\/#primaryimage"},"thumbnailUrl":"https:\/\/amamsul.meutecnicoremoto.com.br\/wp-content\/uploads\/2024\/05\/TribunalDoJuri_1.jpg","datePublished":"2024-04-13T15:21:00+00:00","dateModified":"2024-05-29T15:22:38+00:00","author":{"@id":"https:\/\/amamsul.meutecnicoremoto.com.br\/#\/schema\/person\/52d48e1503c287dad33f5b5152a412c3"},"breadcrumb":{"@id":"https:\/\/amamsul.meutecnicoremoto.com.br\/index.php\/2024\/04\/13\/tjms-e-destaque-nacional-na-realizacao-de-juris\/#breadcrumb"},"inLanguage":"pt-BR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/amamsul.meutecnicoremoto.com.br\/index.php\/2024\/04\/13\/tjms-e-destaque-nacional-na-realizacao-de-juris\/"]}]},{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/amamsul.meutecnicoremoto.com.br\/index.php\/2024\/04\/13\/tjms-e-destaque-nacional-na-realizacao-de-juris\/#primaryimage","url":"https:\/\/amamsul.meutecnicoremoto.com.br\/wp-content\/uploads\/2024\/05\/TribunalDoJuri_1.jpg","contentUrl":"https:\/\/amamsul.meutecnicoremoto.com.br\/wp-content\/uploads\/2024\/05\/TribunalDoJuri_1.jpg","width":1080,"height":720,"caption":"xr:d:DAGCTRkvWsw:2,j:2176789266169390485,t:24041313"},{"@type":"BreadcrumbList","@id":"https:\/\/amamsul.meutecnicoremoto.com.br\/index.php\/2024\/04\/13\/tjms-e-destaque-nacional-na-realizacao-de-juris\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"In\u00edcio","item":"https:\/\/amamsul.meutecnicoremoto.com.br\/"},{"@type":"ListItem","position":2,"name":"TJMS \u00e9 destaque nacional na realiza\u00e7\u00e3o de j\u00faris"}]},{"@type":"WebSite","@id":"https:\/\/amamsul.meutecnicoremoto.com.br\/#website","url":"https:\/\/amamsul.meutecnicoremoto.com.br\/","name":"AMAMSUL","description":"Associa\u00e7\u00e3o dos Magistrados de Mato Grosso do Sul","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/amamsul.meutecnicoremoto.com.br\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"pt-BR"},{"@type":"Person","@id":"https:\/\/amamsul.meutecnicoremoto.com.br\/#\/schema\/person\/52d48e1503c287dad33f5b5152a412c3","name":"hermes","image":{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/amamsul.meutecnicoremoto.com.br\/#\/schema\/person\/image\/","url":"https:\/\/secure.gravatar.com\/avatar\/39483e59aab29b78c1c51fa7c391c7ea16952951fc2d61ae410507457c09593d?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/39483e59aab29b78c1c51fa7c391c7ea16952951fc2d61ae410507457c09593d?s=96&d=mm&r=g","caption":"hermes"},"sameAs":["https:\/\/amamsul.meutecnicoremoto.com.br"],"url":"https:\/\/amamsul.meutecnicoremoto.com.br\/index.php\/author\/hermes\/"}]}},"_links":{"self":[{"href":"https:\/\/amamsul.meutecnicoremoto.com.br\/index.php\/wp-json\/wp\/v2\/posts\/1638","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/amamsul.meutecnicoremoto.com.br\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/amamsul.meutecnicoremoto.com.br\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/amamsul.meutecnicoremoto.com.br\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/amamsul.meutecnicoremoto.com.br\/index.php\/wp-json\/wp\/v2\/comments?post=1638"}],"version-history":[{"count":1,"href":"https:\/\/amamsul.meutecnicoremoto.com.br\/index.php\/wp-json\/wp\/v2\/posts\/1638\/revisions"}],"predecessor-version":[{"id":1641,"href":"https:\/\/amamsul.meutecnicoremoto.com.br\/index.php\/wp-json\/wp\/v2\/posts\/1638\/revisions\/1641"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/amamsul.meutecnicoremoto.com.br\/index.php\/wp-json\/wp\/v2\/media\/1640"}],"wp:attachment":[{"href":"https:\/\/amamsul.meutecnicoremoto.com.br\/index.php\/wp-json\/wp\/v2\/media?parent=1638"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/amamsul.meutecnicoremoto.com.br\/index.php\/wp-json\/wp\/v2\/categories?post=1638"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/amamsul.meutecnicoremoto.com.br\/index.php\/wp-json\/wp\/v2\/tags?post=1638"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}