{"id":1469,"date":"2022-09-26T10:14:00","date_gmt":"2022-09-26T13:14:00","guid":{"rendered":"https:\/\/amamsul.meutecnicoremoto.com.br\/?p=1469"},"modified":"2023-08-29T10:15:21","modified_gmt":"2023-08-29T13:15:21","slug":"eu-juiza-apresenta-juiza-substituta-designada-para-atuar-em-navirai","status":"publish","type":"post","link":"https:\/\/amamsul.meutecnicoremoto.com.br\/index.php\/2022\/09\/26\/eu-juiza-apresenta-juiza-substituta-designada-para-atuar-em-navirai\/","title":{"rendered":"Eu, Ju\u00edza apresenta ju\u00edza substituta designada para atuar em Navira\u00ed"},"content":{"rendered":"\n<p>Em continuidade \u00e0 proposta de retomada do Eu Ju\u00edza, a Associa\u00e7\u00e3o dos Magistrados de MS apresenta a ju\u00edza substituta Monique Rafaele Antunes. Ressalte-se que a inten\u00e7\u00e3o \u00e9 valorizar a mulher que integra a magistratura sul-mato-grossense. Em raz\u00e3o da grande repercuss\u00e3o na sociedade, por permitir que a popula\u00e7\u00e3o conhe\u00e7a as mulheres fortes, inteligentes e capazes que fazem parte a magistratura de MS, a a\u00e7\u00e3o foi retomada.<\/p>\n\n\n\n<p>O projeto, que homenageia cada mulher magistrada, sua hist\u00f3ria e trajet\u00f3ria na justi\u00e7a de MS, foi criado no bi\u00eanio 2019\/2020 pela ent\u00e3o ocupante da diretoria, desembargadora aposentada Maria Isabel de Matos Rocha.<\/p>\n\n\n\n<p>Al\u00e9m disso, a nova edi\u00e7\u00e3o do \u201cEu, Ju\u00edza\u201d abre espa\u00e7o para as magistradas que n\u00e3o puderam participar da primeira rodada de entrevistas. Ao final, as entrevistas ser\u00e3o parte de um livro &#8211; um registro hist\u00f3rico, nunca feito de forma t\u00e3o particularizada pela entidade associativa.<\/p>\n\n\n\n<p>Conhe\u00e7a a nova ju\u00edza de Mato Grosso do Sul.<\/p>\n\n\n\n<p><strong><em>1) Qual a data de seu ingresso na magistratura?<\/em><\/strong><br>27.04.2022<\/p>\n\n\n\n<p><strong><em>2) Est\u00e1 em exerc\u00edcio ou j\u00e1 se aposentou?<\/em><\/strong><br>Em exerc\u00edcio.<\/p>\n\n\n\n<p><strong><em>3) Como foi sua posse?<\/em><\/strong><br>Foi uma solenidade muito bonita e emocionante. A presen\u00e7a dos meus pais, em especial, foi muito gratificante, pois poder proporcionar esse momento para eles tornou tudo ainda mais \u00fanico. A posse materializa a realiza\u00e7\u00e3o de um sonho e a cerim\u00f4nia realizada pelo TJMS refletiu muito bem essa particularidade. Foi um momento festivo, de comemora\u00e7\u00e3o e integra\u00e7\u00e3o com os novos colegas de turma e de carreira, mas tamb\u00e9m representou a assun\u00e7\u00e3o da responsabilidade inerente ao cargo. O querido colega e amigo Pedro Campos, respons\u00e1vel pelo discurso de posse, sintetizou bem: foi um dia de agradecimento, de reconhecimento e de comprometimento.<\/p>\n\n\n\n<p><em><strong>4) Como foi seu primeiro dia de ju\u00edza?<\/strong><\/em><br>Ap\u00f3s tr\u00eas meses de curso de forma\u00e7\u00e3o passei a coadjuvar com a 1\u00aa Vara C\u00edvel da comarca de Navira\u00ed. O primeiro dia j\u00e1 foi de muito trabalho e marcou o in\u00edcio efetivo do meu dever de servir ao jurisdicionado do Estado de Mato Grosso do Sul.<\/p>\n\n\n\n<p><strong><em>5) Qual foi seu dia mais feliz de magistrada?<\/em><\/strong><br>Estou em in\u00edcio de carreira, ent\u00e3o o dia da posse, com certeza, foi o mais marcante at\u00e9 agora. Posso dizer, contudo, que os meus dias de ju\u00edza est\u00e3o sendo felizes, estou fazendo um trabalho que amo e para o qual dediquei muitos anos de estudo.<\/p>\n\n\n\n<p><strong><em>6) Qual foi a a\u00e7\u00e3o mais significativa ou decis\u00e3o mais marcante da qual se orgulha?<\/em><\/strong><br>Tento todos os dias proferir decis\u00f5es com o m\u00e1ximo respeito \u00e0 Lei, \u00e0 Constitui\u00e7\u00e3o e ao jurisdicionado. As decis\u00f5es prolatadas pelos ju\u00edzes, por mais simples que sejam os casos, tem o potencial de atingir e modificar a vida das pessoas. \u00c9 uma responsabilidade enorme, mas poder realizar esse trabalho com dignidade e respeito \u00e9, por si s\u00f3, motivo de orgulho.<\/p>\n\n\n\n<p><strong><em>7) O que mais a comoveu na atua\u00e7\u00e3o como ju\u00edza?<\/em><\/strong><br>Durante o curso de forma\u00e7\u00e3o, na etapa da pr\u00e1tica judicante, tive a oportunidade de encaminhar pessoalmente quatro irm\u00e3os, um deles com 17 anos, para os pais adotivos. Os irm\u00e3os passaram por todo tipo de viol\u00eancia e neglig\u00eancia por parte dos pais biol\u00f3gicos e naquele momento estavam com uma vida nova come\u00e7ando. Foi um encontro emocionante entre pais e filhos. Recentemente tive not\u00edcias da fam\u00edlia e est\u00e1 tudo dando certo, todos adaptados e felizes.<\/p>\n\n\n\n<p><strong><em>8) Qual seu sonho de magistrada?<\/em><\/strong><br>Um magistrado \u00e9, acima de tudo, um servidor p\u00fablico. Assim, meu sonho como magistrada \u00e9 o de cumprir o meu dever de servir o jurisdicionado da melhor forma poss\u00edvel, garantindo presteza e efetividade na entrega da presta\u00e7\u00e3o jurisdicional.<\/p>\n\n\n\n<p><strong><em>9) O que gosta de fazer no tempo livre?<\/em><\/strong><br>Estar em fam\u00edlia, viajar, cozinhar e ler.<\/p>\n\n\n\n<p><em><strong>10) Qual seu desafio pessoal e\/ou profissional mais relevante?<\/strong><\/em><br>Acredito que tentar conciliar a vida pessoal com a profissional, pois o trabalho demanda muita dedica\u00e7\u00e3o, \u00e9 um grande desafio. Especificamente no campo profissional, a necessidade de cumprimento de metas aliada ao volume de trabalho \u00e9 uma dificuldade di\u00e1ria para os magistrados e demais servidores e precisa ser enfrentada com estrat\u00e9gia, sem perda de qualidade do trabalho e sem sobrecarregar a equipe.<br>Outro desafio \u00e9 a necessidade de constante atualiza\u00e7\u00e3o para acompanhar a intensa mudan\u00e7a e transforma\u00e7\u00e3o que a nossa sociedade tem vivenciado. Essas transforma\u00e7\u00f5es est\u00e3o a demandar respostas por parte dos profissionais do direito para solucionar situa\u00e7\u00f5es que at\u00e9 ent\u00e3o eram inexistentes, como os crimes que ocorrem em ambiente virtual, por exemplo.<\/p>\n\n\n\n<p><em><strong>11) Cite uma mulher inspiradora, brasileira ou n\u00e3o<\/strong><\/em><br>Minha m\u00e3e \u00e9 uma mulher que enfrentou muitas dificuldades e sempre se manteve forte para garantir o melhor para mim e meu irm\u00e3o. \u00c9 realmente uma mulher inspiradora.<\/p>\n\n\n\n<p><em><strong>12) Cite uma mulher inspiradora que exerce ou exerceu um cargo no Poder Judici\u00e1rio<\/strong><\/em><br>A Desa Thereza Gris\u00f3lia Tang. Ela foi a primeira mulher a ocupar os cargos de ju\u00edza, desembargadora, Corregedora-Geral e Presidente de um Tribunal de Justi\u00e7a no pa\u00eds. A Desa Thereza sempre esteve na vanguarda e serve de inspira\u00e7\u00e3o para todas as mulheres que queiram exercer algum cargo no Poder Judici\u00e1rio. Contudo, gostaria de aproveitar o ensejo para homenagear tamb\u00e9m as ju\u00edzas do TJMS com quem tive contato durante o per\u00edodo de pr\u00e1tica judicante e que, gentilmente, compartilharam experi\u00eancia e conhecimento. S\u00e3o todas fontes di\u00e1rias de inspira\u00e7\u00e3o.<\/p>\n\n\n\n<p><strong><em>13) O que diria hoje em uma frase a uma mulher que quer ser ju\u00edza?<\/em><\/strong><br>O caminho at\u00e9 a aprova\u00e7\u00e3o \u00e9 \u00e1rduo, exige muita dedica\u00e7\u00e3o, abdica\u00e7\u00e3o e intelig\u00eancia emocional, mas a recompensa faz todo o esfor\u00e7o valer a pena. Acrescento que a aprova\u00e7\u00e3o \u00e9 apenas uma etapa dessa jornada e que a magistratura exige voca\u00e7\u00e3o, ren\u00fancias e senso de dever. Ent\u00e3o minha frase \u00e9: se voc\u00ea acredita que est\u00e1 vocacionada para a magistratura tenha resili\u00eancia, dedica\u00e7\u00e3o e perseveran\u00e7a.<\/p>\n\n\n\n<p><em><strong>14) Diga uma frase que a define como mulher magistrada<\/strong><\/em><br>\u00c9 uma tarefa muito dif\u00edcil tentar me definir como uma mulher magistrada, sobretudo por ainda ser nova na carreira, mas busco os ideais de S\u00f3crates na minha judicatura, porquanto pretendo ser uma ju\u00edza que saiba escutar com cortesia e que atue sempre imbu\u00edda pela temperan\u00e7a, prud\u00eancia, sobriedade e imparcialidade para melhor servir ao jurisdicionado sul-mato-grossense.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Em continuidade \u00e0 proposta de retomada do Eu Ju\u00edza, a Associa\u00e7\u00e3o dos Magistrados de MS apresenta a ju\u00edza substituta Monique Rafaele Antunes. Ressalte-se que a inten\u00e7\u00e3o \u00e9 valorizar a mulher que integra a magistratura sul-mato-grossense. Em raz\u00e3o da grande repercuss\u00e3o na sociedade, por permitir que a popula\u00e7\u00e3o conhe\u00e7a as mulheres fortes, inteligentes e capazes que [&hellip;]<\/p>\n","protected":false},"author":2,"featured_media":1470,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[5],"tags":[],"class_list":["post-1469","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-noticias"],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v22.6 (Yoast SEO v26.9) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>Eu, Ju\u00edza apresenta ju\u00edza substituta designada para atuar em Navira\u00ed - AMAMSUL<\/title>\n<meta name=\"robots\" content=\"noindex, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<meta property=\"og:locale\" content=\"pt_BR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Eu, Ju\u00edza apresenta ju\u00edza substituta designada para atuar em Navira\u00ed\" \/>\n<meta property=\"og:description\" content=\"Em continuidade \u00e0 proposta de retomada do Eu Ju\u00edza, a Associa\u00e7\u00e3o dos Magistrados de MS apresenta a ju\u00edza substituta Monique Rafaele Antunes. Ressalte-se que a inten\u00e7\u00e3o \u00e9 valorizar a mulher que integra a magistratura sul-mato-grossense. Em raz\u00e3o da grande repercuss\u00e3o na sociedade, por permitir que a popula\u00e7\u00e3o conhe\u00e7a as mulheres fortes, inteligentes e capazes que [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/amamsul.meutecnicoremoto.com.br\/index.php\/2022\/09\/26\/eu-juiza-apresenta-juiza-substituta-designada-para-atuar-em-navirai\/\" \/>\n<meta property=\"og:site_name\" content=\"AMAMSUL\" \/>\n<meta property=\"article:published_time\" content=\"2022-09-26T13:14:00+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2023-08-29T13:15:21+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/amamsul.meutecnicoremoto.com.br\/wp-content\/uploads\/2023\/08\/moniqueeujuiza.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"800\" \/>\n\t<meta property=\"og:image:height\" content=\"550\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Imprensa Amamsul\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Imprensa Amamsul\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. tempo de leitura\" \/>\n\t<meta name=\"twitter:data2\" content=\"6 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\/\/amamsul.meutecnicoremoto.com.br\/index.php\/2022\/09\/26\/eu-juiza-apresenta-juiza-substituta-designada-para-atuar-em-navirai\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/amamsul.meutecnicoremoto.com.br\/index.php\/2022\/09\/26\/eu-juiza-apresenta-juiza-substituta-designada-para-atuar-em-navirai\/\"},\"author\":{\"name\":\"Imprensa Amamsul\",\"@id\":\"https:\/\/amamsul.meutecnicoremoto.com.br\/#\/schema\/person\/646bfbd1aa4c9c8dc837ed1b59b63b7c\"},\"headline\":\"Eu, Ju\u00edza apresenta ju\u00edza substituta designada para atuar em Navira\u00ed\",\"datePublished\":\"2022-09-26T13:14:00+00:00\",\"dateModified\":\"2023-08-29T13:15:21+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/amamsul.meutecnicoremoto.com.br\/index.php\/2022\/09\/26\/eu-juiza-apresenta-juiza-substituta-designada-para-atuar-em-navirai\/\"},\"wordCount\":1093,\"commentCount\":0,\"image\":{\"@id\":\"https:\/\/amamsul.meutecnicoremoto.com.br\/index.php\/2022\/09\/26\/eu-juiza-apresenta-juiza-substituta-designada-para-atuar-em-navirai\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/amamsul.meutecnicoremoto.com.br\/wp-content\/uploads\/2023\/08\/moniqueeujuiza.jpg\",\"articleSection\":[\"Not\u00edcias\"],\"inLanguage\":\"pt-BR\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\/\/amamsul.meutecnicoremoto.com.br\/index.php\/2022\/09\/26\/eu-juiza-apresenta-juiza-substituta-designada-para-atuar-em-navirai\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/amamsul.meutecnicoremoto.com.br\/index.php\/2022\/09\/26\/eu-juiza-apresenta-juiza-substituta-designada-para-atuar-em-navirai\/\",\"url\":\"https:\/\/amamsul.meutecnicoremoto.com.br\/index.php\/2022\/09\/26\/eu-juiza-apresenta-juiza-substituta-designada-para-atuar-em-navirai\/\",\"name\":\"Eu, Ju\u00edza apresenta ju\u00edza substituta designada para atuar em Navira\u00ed - AMAMSUL\",\"isPartOf\":{\"@id\":\"https:\/\/amamsul.meutecnicoremoto.com.br\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/amamsul.meutecnicoremoto.com.br\/index.php\/2022\/09\/26\/eu-juiza-apresenta-juiza-substituta-designada-para-atuar-em-navirai\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/amamsul.meutecnicoremoto.com.br\/index.php\/2022\/09\/26\/eu-juiza-apresenta-juiza-substituta-designada-para-atuar-em-navirai\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/amamsul.meutecnicoremoto.com.br\/wp-content\/uploads\/2023\/08\/moniqueeujuiza.jpg\",\"datePublished\":\"2022-09-26T13:14:00+00:00\",\"dateModified\":\"2023-08-29T13:15:21+00:00\",\"author\":{\"@id\":\"https:\/\/amamsul.meutecnicoremoto.com.br\/#\/schema\/person\/646bfbd1aa4c9c8dc837ed1b59b63b7c\"},\"breadcrumb\":{\"@id\":\"https:\/\/amamsul.meutecnicoremoto.com.br\/index.php\/2022\/09\/26\/eu-juiza-apresenta-juiza-substituta-designada-para-atuar-em-navirai\/#breadcrumb\"},\"inLanguage\":\"pt-BR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/amamsul.meutecnicoremoto.com.br\/index.php\/2022\/09\/26\/eu-juiza-apresenta-juiza-substituta-designada-para-atuar-em-navirai\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\/\/amamsul.meutecnicoremoto.com.br\/index.php\/2022\/09\/26\/eu-juiza-apresenta-juiza-substituta-designada-para-atuar-em-navirai\/#primaryimage\",\"url\":\"https:\/\/amamsul.meutecnicoremoto.com.br\/wp-content\/uploads\/2023\/08\/moniqueeujuiza.jpg\",\"contentUrl\":\"https:\/\/amamsul.meutecnicoremoto.com.br\/wp-content\/uploads\/2023\/08\/moniqueeujuiza.jpg\",\"width\":800,\"height\":550},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/amamsul.meutecnicoremoto.com.br\/index.php\/2022\/09\/26\/eu-juiza-apresenta-juiza-substituta-designada-para-atuar-em-navirai\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"In\u00edcio\",\"item\":\"https:\/\/amamsul.meutecnicoremoto.com.br\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Eu, Ju\u00edza apresenta ju\u00edza substituta designada para atuar em Navira\u00ed\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/amamsul.meutecnicoremoto.com.br\/#website\",\"url\":\"https:\/\/amamsul.meutecnicoremoto.com.br\/\",\"name\":\"AMAMSUL\",\"description\":\"Associa\u00e7\u00e3o dos Magistrados de Mato Grosso do Sul\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/amamsul.meutecnicoremoto.com.br\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"pt-BR\"},{\"@type\":\"Person\",\"@id\":\"https:\/\/amamsul.meutecnicoremoto.com.br\/#\/schema\/person\/646bfbd1aa4c9c8dc837ed1b59b63b7c\",\"name\":\"Imprensa Amamsul\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\/\/amamsul.meutecnicoremoto.com.br\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/62be2d8c4f042719726d6b6a4e1a0942261c1a03354967aa17e58b127147014f?s=96&d=mm&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/62be2d8c4f042719726d6b6a4e1a0942261c1a03354967aa17e58b127147014f?s=96&d=mm&r=g\",\"caption\":\"Imprensa Amamsul\"},\"url\":\"https:\/\/amamsul.meutecnicoremoto.com.br\/index.php\/author\/imprensa-amamsul\/\"}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"Eu, Ju\u00edza apresenta ju\u00edza substituta designada para atuar em Navira\u00ed - AMAMSUL","robots":{"index":"noindex","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"og_locale":"pt_BR","og_type":"article","og_title":"Eu, Ju\u00edza apresenta ju\u00edza substituta designada para atuar em Navira\u00ed","og_description":"Em continuidade \u00e0 proposta de retomada do Eu Ju\u00edza, a Associa\u00e7\u00e3o dos Magistrados de MS apresenta a ju\u00edza substituta Monique Rafaele Antunes. Ressalte-se que a inten\u00e7\u00e3o \u00e9 valorizar a mulher que integra a magistratura sul-mato-grossense. Em raz\u00e3o da grande repercuss\u00e3o na sociedade, por permitir que a popula\u00e7\u00e3o conhe\u00e7a as mulheres fortes, inteligentes e capazes que [&hellip;]","og_url":"https:\/\/amamsul.meutecnicoremoto.com.br\/index.php\/2022\/09\/26\/eu-juiza-apresenta-juiza-substituta-designada-para-atuar-em-navirai\/","og_site_name":"AMAMSUL","article_published_time":"2022-09-26T13:14:00+00:00","article_modified_time":"2023-08-29T13:15:21+00:00","og_image":[{"width":800,"height":550,"url":"https:\/\/amamsul.meutecnicoremoto.com.br\/wp-content\/uploads\/2023\/08\/moniqueeujuiza.jpg","type":"image\/jpeg"}],"author":"Imprensa Amamsul","twitter_card":"summary_large_image","twitter_misc":{"Escrito por":"Imprensa Amamsul","Est. tempo de leitura":"6 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/amamsul.meutecnicoremoto.com.br\/index.php\/2022\/09\/26\/eu-juiza-apresenta-juiza-substituta-designada-para-atuar-em-navirai\/#article","isPartOf":{"@id":"https:\/\/amamsul.meutecnicoremoto.com.br\/index.php\/2022\/09\/26\/eu-juiza-apresenta-juiza-substituta-designada-para-atuar-em-navirai\/"},"author":{"name":"Imprensa Amamsul","@id":"https:\/\/amamsul.meutecnicoremoto.com.br\/#\/schema\/person\/646bfbd1aa4c9c8dc837ed1b59b63b7c"},"headline":"Eu, Ju\u00edza apresenta ju\u00edza substituta designada para atuar em Navira\u00ed","datePublished":"2022-09-26T13:14:00+00:00","dateModified":"2023-08-29T13:15:21+00:00","mainEntityOfPage":{"@id":"https:\/\/amamsul.meutecnicoremoto.com.br\/index.php\/2022\/09\/26\/eu-juiza-apresenta-juiza-substituta-designada-para-atuar-em-navirai\/"},"wordCount":1093,"commentCount":0,"image":{"@id":"https:\/\/amamsul.meutecnicoremoto.com.br\/index.php\/2022\/09\/26\/eu-juiza-apresenta-juiza-substituta-designada-para-atuar-em-navirai\/#primaryimage"},"thumbnailUrl":"https:\/\/amamsul.meutecnicoremoto.com.br\/wp-content\/uploads\/2023\/08\/moniqueeujuiza.jpg","articleSection":["Not\u00edcias"],"inLanguage":"pt-BR","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/amamsul.meutecnicoremoto.com.br\/index.php\/2022\/09\/26\/eu-juiza-apresenta-juiza-substituta-designada-para-atuar-em-navirai\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/amamsul.meutecnicoremoto.com.br\/index.php\/2022\/09\/26\/eu-juiza-apresenta-juiza-substituta-designada-para-atuar-em-navirai\/","url":"https:\/\/amamsul.meutecnicoremoto.com.br\/index.php\/2022\/09\/26\/eu-juiza-apresenta-juiza-substituta-designada-para-atuar-em-navirai\/","name":"Eu, Ju\u00edza apresenta ju\u00edza substituta designada para atuar em Navira\u00ed - AMAMSUL","isPartOf":{"@id":"https:\/\/amamsul.meutecnicoremoto.com.br\/#website"},"primaryImageOfPage":{"@id":"https:\/\/amamsul.meutecnicoremoto.com.br\/index.php\/2022\/09\/26\/eu-juiza-apresenta-juiza-substituta-designada-para-atuar-em-navirai\/#primaryimage"},"image":{"@id":"https:\/\/amamsul.meutecnicoremoto.com.br\/index.php\/2022\/09\/26\/eu-juiza-apresenta-juiza-substituta-designada-para-atuar-em-navirai\/#primaryimage"},"thumbnailUrl":"https:\/\/amamsul.meutecnicoremoto.com.br\/wp-content\/uploads\/2023\/08\/moniqueeujuiza.jpg","datePublished":"2022-09-26T13:14:00+00:00","dateModified":"2023-08-29T13:15:21+00:00","author":{"@id":"https:\/\/amamsul.meutecnicoremoto.com.br\/#\/schema\/person\/646bfbd1aa4c9c8dc837ed1b59b63b7c"},"breadcrumb":{"@id":"https:\/\/amamsul.meutecnicoremoto.com.br\/index.php\/2022\/09\/26\/eu-juiza-apresenta-juiza-substituta-designada-para-atuar-em-navirai\/#breadcrumb"},"inLanguage":"pt-BR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/amamsul.meutecnicoremoto.com.br\/index.php\/2022\/09\/26\/eu-juiza-apresenta-juiza-substituta-designada-para-atuar-em-navirai\/"]}]},{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/amamsul.meutecnicoremoto.com.br\/index.php\/2022\/09\/26\/eu-juiza-apresenta-juiza-substituta-designada-para-atuar-em-navirai\/#primaryimage","url":"https:\/\/amamsul.meutecnicoremoto.com.br\/wp-content\/uploads\/2023\/08\/moniqueeujuiza.jpg","contentUrl":"https:\/\/amamsul.meutecnicoremoto.com.br\/wp-content\/uploads\/2023\/08\/moniqueeujuiza.jpg","width":800,"height":550},{"@type":"BreadcrumbList","@id":"https:\/\/amamsul.meutecnicoremoto.com.br\/index.php\/2022\/09\/26\/eu-juiza-apresenta-juiza-substituta-designada-para-atuar-em-navirai\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"In\u00edcio","item":"https:\/\/amamsul.meutecnicoremoto.com.br\/"},{"@type":"ListItem","position":2,"name":"Eu, Ju\u00edza apresenta ju\u00edza substituta designada para atuar em Navira\u00ed"}]},{"@type":"WebSite","@id":"https:\/\/amamsul.meutecnicoremoto.com.br\/#website","url":"https:\/\/amamsul.meutecnicoremoto.com.br\/","name":"AMAMSUL","description":"Associa\u00e7\u00e3o dos Magistrados de Mato Grosso do Sul","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/amamsul.meutecnicoremoto.com.br\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"pt-BR"},{"@type":"Person","@id":"https:\/\/amamsul.meutecnicoremoto.com.br\/#\/schema\/person\/646bfbd1aa4c9c8dc837ed1b59b63b7c","name":"Imprensa Amamsul","image":{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/amamsul.meutecnicoremoto.com.br\/#\/schema\/person\/image\/","url":"https:\/\/secure.gravatar.com\/avatar\/62be2d8c4f042719726d6b6a4e1a0942261c1a03354967aa17e58b127147014f?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/62be2d8c4f042719726d6b6a4e1a0942261c1a03354967aa17e58b127147014f?s=96&d=mm&r=g","caption":"Imprensa Amamsul"},"url":"https:\/\/amamsul.meutecnicoremoto.com.br\/index.php\/author\/imprensa-amamsul\/"}]}},"_links":{"self":[{"href":"https:\/\/amamsul.meutecnicoremoto.com.br\/index.php\/wp-json\/wp\/v2\/posts\/1469","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/amamsul.meutecnicoremoto.com.br\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/amamsul.meutecnicoremoto.com.br\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/amamsul.meutecnicoremoto.com.br\/index.php\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/amamsul.meutecnicoremoto.com.br\/index.php\/wp-json\/wp\/v2\/comments?post=1469"}],"version-history":[{"count":1,"href":"https:\/\/amamsul.meutecnicoremoto.com.br\/index.php\/wp-json\/wp\/v2\/posts\/1469\/revisions"}],"predecessor-version":[{"id":1471,"href":"https:\/\/amamsul.meutecnicoremoto.com.br\/index.php\/wp-json\/wp\/v2\/posts\/1469\/revisions\/1471"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/amamsul.meutecnicoremoto.com.br\/index.php\/wp-json\/wp\/v2\/media\/1470"}],"wp:attachment":[{"href":"https:\/\/amamsul.meutecnicoremoto.com.br\/index.php\/wp-json\/wp\/v2\/media?parent=1469"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/amamsul.meutecnicoremoto.com.br\/index.php\/wp-json\/wp\/v2\/categories?post=1469"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/amamsul.meutecnicoremoto.com.br\/index.php\/wp-json\/wp\/v2\/tags?post=1469"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}